{"id":3572,"date":"2017-02-16T16:21:44","date_gmt":"2017-02-16T20:21:44","guid":{"rendered":"http:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902.jpg"},"modified":"2017-02-16T16:21:44","modified_gmt":"2017-02-16T20:21:44","slug":"img_20161024_081902-jpg","status":"inherit","type":"attachment","link":"https:\/\/beveragewarehousevt.com\/home\/img_20161024_081902-jpg\/","title":{"rendered":"img_20161024_081902.jpg"},"author":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"smush":"Not processed","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902.jpg'><img width=\"300\" height=\"201\" src=\"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-300x201.jpg 300w, https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-768x514.jpg 768w, https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-1024x686.jpg 1024w, https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":857,"file":"2017\/02\/img_20161024_081902.jpg","sizes":{"thumbnail":{"file":"img_20161024_081902-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-150x150.jpg"},"medium":{"file":"img_20161024_081902-300x201.jpg","width":300,"height":201,"mime_type":"image\/jpeg","source_url":"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-300x201.jpg"},"medium_large":{"file":"img_20161024_081902-768x514.jpg","width":768,"height":514,"mime_type":"image\/jpeg","source_url":"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-768x514.jpg"},"large":{"file":"img_20161024_081902-1024x686.jpg","width":1024,"height":686,"mime_type":"image\/jpeg","source_url":"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-1024x686.jpg"},"post-thumbnail":{"file":"img_20161024_081902-672x372.jpg","width":672,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-672x372.jpg"},"twentyfourteen-full-width":{"file":"img_20161024_081902-1038x576.jpg","width":1038,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902-1038x576.jpg"},"full":{"file":"img_20161024_081902.jpg","width":1280,"height":857,"mime_type":"image\/jpeg","source_url":"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/beveragewarehousevt.com\/home\/wp-content\/uploads\/2017\/02\/img_20161024_081902.jpg","_links":{"self":[{"href":"https:\/\/beveragewarehousevt.com\/home\/wp-json\/wp\/v2\/media\/3572"}],"collection":[{"href":"https:\/\/beveragewarehousevt.com\/home\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beveragewarehousevt.com\/home\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beveragewarehousevt.com\/home\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/beveragewarehousevt.com\/home\/wp-json\/wp\/v2\/comments?post=3572"}]}}